{"id":58781,"date":"2017-06-09T16:37:51","date_gmt":"2017-06-09T16:37:51","guid":{"rendered":"https:\/\/mk-solutions.com\/?page_id=58781\/"},"modified":"2023-03-20T15:07:57","modified_gmt":"2023-03-20T14:07:57","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/www.mksolutions.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p><\/p>\n<p>[vc_section back_color=&#8221;color-lxmt&#8221; overlay_alpha=&#8221;50&#8243; el_class=&#8221;contact-world-map&#8221;][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;3&#8243; bottom_padding=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243;][vc_column column_width_use_pixel=&#8221;yes&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; column_width_pixel=&#8221;700&#8243;][vc_raw_js]JTNDc2NyaXB0JTNFJTBBalF1ZXJ5JTI4ZnVuY3Rpb24lMjglMjQlMjklN0IlMEElMEElMjQlMjglMjcubW9iaWxlLWxvY2F0aW9uLXRvZ2dsZSUyNyUyOS5jbGljayUyOGZ1bmN0aW9uJTI4JTI5JTdCJTBBJTA5JTI0JTI4dGhpcyUyOS5uZXh0JTI4JTI3LmxvY2F0aW9uLWxpc3QlMjclMjkuc2xpZGVUb2dnbGUlMjg1MDAlMjklM0IlMEElMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjAlMjQlMjh0aGlzJTI5LnRvZ2dsZUNsYXNzJTI4JTI3Y2xpY2tlZCUyNyUyOSUzQiUwQSU3RCUyOSUzQiUwQSUwQSU3RCUyOSUzQiUyMCUyRiUyRmpRdWVyeSUyMGZ1bmN0aW9uJTBBJTNDJTJGc2NyaXB0JTNF[\/vc_raw_js][vc_custom_heading subheading=&#8221;We are active at many locations worldwide. Choose your location below!&#8221; uncode_shortcode_id=&#8221;660860&#8243;]Contact us.[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; equal_height=&#8221;yes&#8221; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243;][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-gyho&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1497346929499{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;}&#8221;][vc_icon icon=&#8221;fa fa-map-pin&#8221; icon_color=&#8221;accent&#8221; size=&#8221;fa-4x&#8221; text_size=&#8221;h5&#8243; title=&#8221;Germany&#8221; uncode_shortcode_id=&#8221;196043&#8243; icon_color_type=&#8221;uncode-palette&#8221;]Here you can find all the important information about our location in Germany.[\/vc_icon][vc_button button_color=&#8221;accent&#8221; radius=&#8221;btn-circle&#8221; border_width=&#8221;0&#8243; link=&#8221;url:%2Fkontakt%2Fde%3Flocation%3Dgermany|||&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;165690&#8243;]Contact[\/vc_button][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-gyho&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1497347083511{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;}&#8221;][vc_icon icon=&#8221;fa fa-map-pin&#8221; icon_color=&#8221;accent&#8221; size=&#8221;fa-4x&#8221; text_size=&#8221;h5&#8243; title=&#8221;USA&#8221; uncode_shortcode_id=&#8221;163619&#8243; icon_color_type=&#8221;uncode-palette&#8221;]Here you can find all the important information about our location in the USA.[\/vc_icon][vc_button button_color=&#8221;accent&#8221; radius=&#8221;btn-circle&#8221; border_width=&#8221;0&#8243; link=&#8221;url:%2Fde%2Fkontakt%2Fus%3Flocation%3Dusa|||&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;325181&#8243;]Contact[\/vc_button][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; override_padding=&#8221;yes&#8221; column_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-gyho&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; css=&#8221;.vc_custom_1497347222144{border-top-width: 1px !important;border-right-width: 1px !important;border-bottom-width: 1px !important;border-left-width: 1px !important;}&#8221;][vc_icon icon=&#8221;fa fa-map-pin&#8221; icon_color=&#8221;accent&#8221; size=&#8221;fa-4x&#8221; text_size=&#8221;h5&#8243; title=&#8221;Denmark&#8221; uncode_shortcode_id=&#8221;146893&#8243; icon_color_type=&#8221;uncode-palette&#8221;]Here you can find all the important information about our location in Denmark.[\/vc_icon][vc_button button_color=&#8221;accent&#8221; radius=&#8221;btn-circle&#8221; border_width=&#8221;0&#8243; link=&#8221;url:%2Fde%2Fkontakt%2Fdnk%3Flocation%3Ddenmark|||&#8221; button_color_type=&#8221;uncode-palette&#8221; uncode_shortcode_id=&#8221;314535&#8243;]Contact[\/vc_button][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;4&#8243; bottom_padding=&#8221;4&#8243; back_image=&#8221;58813&#8243; back_repeat=&#8221;no-repeat&#8221; back_position=&#8221;right top&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; el_class=&#8221;location-list-bg&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_column_text uncode_shortcode_id=&#8221;147111&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">Africa<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">Africa<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=africa\">Africa<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;694050&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">Asia<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">Asia<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/vnm?location=vietnam\">Vietnam<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=asia\">Other countries<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;209384&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">Europe<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">Europe<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=baltic-states\">Baltic states<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=benelux-countries\">Benelux countries<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=germany\">Germany<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=denmark\">Denmark<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=finland\">Finland<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=iceland\">Iceland<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=norway\">Norway<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/pl?location=poland\">Poland<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=portugal\">Portugal<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=russia\">Russia<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/dnk?location=sweden\">Sweden<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=slovakia\">Slovakia<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/esp?location=spain\">Spain<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=czech-republic\">Czech Republic<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=europe\">Other countries<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243;][vc_column_text uncode_shortcode_id=&#8221;138144&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">Middle East<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">Middle East<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/mittlerer-osten\/\">Middle East<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;204649&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">North America<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">North America<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/us?location=canada\">Canada<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/us?location=usa\">USA<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/mex?location=mexico\">Mexico<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;139772&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">South America<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">South America<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/mex?location=south-america\">South America<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;379693&#8243;]<\/p>\n<div class=\"toggle-contact\"><strong><span class=\"map-location-heading\">Oceania<\/span><\/strong><\/div>\n<div class=\"mobile-location-toggle\"><strong><span class=\"map-location-heading\">Oceania<\/span><\/strong><\/div>\n<ul class=\"location-list\">\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=australia\">Australia<\/a><\/li>\n<li><a href=\"https:\/\/www.mksolutions.com\/kontakt\/de?location=new-zealand\">New Zealand<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243; el_class=&#8221;hidden-mobile&#8221;][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_visibility=&#8221;yes&#8221; mobile_width=&#8221;0&#8243; width=&#8221;1\/4&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section overlay_alpha=&#8221;50&#8243; el_id=&#8221;contact&#8221;][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;4&#8243; bottom_padding=&#8221;4&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243;][vc_column column_width_use_pixel=&#8221;yes&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; column_width_pixel=&#8221;700&#8243;][vc_custom_heading heading_semantic=&#8221;h3&#8243; subheading=&#8221;We will be glad to answer any questions arising in connection with our products. Please use<br \/>\nour contact form for your enquiry.&#8221; uncode_shortcode_id=&#8221;187325&#8243; text_color_type=&#8221;uncode-palette&#8221; text_color_solid=&#8221;#ff0000&#8243;]Send us a message.[\/vc_custom_heading][vc_row_inner][vc_column_inner width=&#8221;1\/1&#8243;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f60088-o2\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/58781#wpcf7-f60088-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"60088\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f60088-o2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/>\n<input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:60088,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false}}\" \/>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"name-institution\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Library \/ Institution\" value=\"\" type=\"text\" name=\"name-institution\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-323\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" id=\"anrede\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-323\"><option value=\"Choose your title\">Choose your title<\/option><option value=\"Mr.\">Mr.<\/option><option value=\"Mrs.\">Mrs.<\/option><\/select><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your first name\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your last name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your e-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-telephone\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"text\" name=\"your-telephone\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap country_auto your-country\"><select class=\"wpcf7-form-control wpcf7-select country_auto wpcf7-country_auto wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-country\" ><option value=\"0\" data-id=\"0\" >Select Country<\/option><option value='Afghanistan' data-id='1'>Afghanistan<\/option><option value='Aland Islands' data-id='2'>Aland Islands<\/option><option value='Albania' data-id='3'>Albania<\/option><option value='Algeria' data-id='4'>Algeria<\/option><option value='American Samoa' data-id='5'>American Samoa<\/option><option value='Andorra' data-id='6'>Andorra<\/option><option value='Angola' data-id='7'>Angola<\/option><option value='Anguilla' data-id='8'>Anguilla<\/option><option value='Antarctica' data-id='9'>Antarctica<\/option><option value='Antigua And Barbuda' data-id='10'>Antigua And Barbuda<\/option><option value='Argentina' data-id='11'>Argentina<\/option><option value='Armenia' data-id='12'>Armenia<\/option><option value='Aruba' data-id='13'>Aruba<\/option><option value='Australia' data-id='14'>Australia<\/option><option value='Austria' data-id='15'>Austria<\/option><option value='Azerbaijan' data-id='16'>Azerbaijan<\/option><option value='Bahamas The' data-id='17'>Bahamas The<\/option><option value='Bahrain' data-id='18'>Bahrain<\/option><option value='Bangladesh' data-id='19'>Bangladesh<\/option><option value='Barbados' data-id='20'>Barbados<\/option><option value='Belarus' data-id='21'>Belarus<\/option><option value='Belgium' data-id='22'>Belgium<\/option><option value='Belize' data-id='23'>Belize<\/option><option value='Benin' data-id='24'>Benin<\/option><option value='Bermuda' data-id='25'>Bermuda<\/option><option value='Bhutan' data-id='26'>Bhutan<\/option><option value='Bolivia' data-id='27'>Bolivia<\/option><option value='Bosnia and Herzegovina' data-id='28'>Bosnia and Herzegovina<\/option><option value='Botswana' data-id='29'>Botswana<\/option><option value='Bouvet Island' data-id='30'>Bouvet Island<\/option><option value='Brazil' data-id='31'>Brazil<\/option><option value='British Indian Ocean Territory' data-id='32'>British Indian Ocean Territory<\/option><option value='Brunei' data-id='33'>Brunei<\/option><option value='Bulgaria' data-id='34'>Bulgaria<\/option><option value='Burkina Faso' data-id='35'>Burkina Faso<\/option><option value='Burundi' data-id='36'>Burundi<\/option><option value='Cambodia' data-id='37'>Cambodia<\/option><option value='Cameroon' data-id='38'>Cameroon<\/option><option value='Canada' data-id='39'>Canada<\/option><option value='Cape Verde' data-id='40'>Cape Verde<\/option><option value='Cayman Islands' data-id='41'>Cayman Islands<\/option><option value='Central African Republic' data-id='42'>Central African Republic<\/option><option value='Chad' data-id='43'>Chad<\/option><option value='Chile' data-id='44'>Chile<\/option><option value='China' data-id='45'>China<\/option><option value='Christmas Island' data-id='46'>Christmas Island<\/option><option value='Cocos (Keeling) Islands' data-id='47'>Cocos (Keeling) Islands<\/option><option value='Colombia' data-id='48'>Colombia<\/option><option value='Comoros' data-id='49'>Comoros<\/option><option value='Congo' data-id='50'>Congo<\/option><option value='Congo The Democratic Republic Of The' data-id='51'>Congo The Democratic Republic Of The<\/option><option value='Cook Islands' data-id='52'>Cook Islands<\/option><option value='Costa Rica' data-id='53'>Costa Rica<\/option><option value='Cote D&#039;Ivoire (Ivory Coast)' data-id='54'>Cote D&#039;Ivoire (Ivory Coast)<\/option><option value='Croatia (Hrvatska)' data-id='55'>Croatia (Hrvatska)<\/option><option value='Cuba' data-id='56'>Cuba<\/option><option value='Cyprus' data-id='57'>Cyprus<\/option><option value='Czech Republic' data-id='58'>Czech Republic<\/option><option value='Denmark' data-id='59'>Denmark<\/option><option value='Djibouti' data-id='60'>Djibouti<\/option><option value='Dominica' data-id='61'>Dominica<\/option><option value='Dominican Republic' data-id='62'>Dominican Republic<\/option><option value='East Timor' data-id='63'>East Timor<\/option><option value='Ecuador' data-id='64'>Ecuador<\/option><option value='Egypt' data-id='65'>Egypt<\/option><option value='El Salvador' data-id='66'>El Salvador<\/option><option value='Equatorial Guinea' data-id='67'>Equatorial Guinea<\/option><option value='Eritrea' data-id='68'>Eritrea<\/option><option value='Estonia' data-id='69'>Estonia<\/option><option value='Ethiopia' data-id='70'>Ethiopia<\/option><option value='Falkland Islands' data-id='71'>Falkland Islands<\/option><option value='Faroe Islands' data-id='72'>Faroe Islands<\/option><option value='Fiji Islands' data-id='73'>Fiji Islands<\/option><option value='Finland' data-id='74'>Finland<\/option><option value='France' data-id='75'>France<\/option><option value='French Guiana' data-id='76'>French Guiana<\/option><option value='French Polynesia' data-id='77'>French Polynesia<\/option><option value='French Southern Territories' data-id='78'>French Southern Territories<\/option><option value='Gabon' data-id='79'>Gabon<\/option><option value='Gambia The' data-id='80'>Gambia The<\/option><option value='Georgia' data-id='81'>Georgia<\/option><option value='Germany' data-id='82'>Germany<\/option><option value='Ghana' data-id='83'>Ghana<\/option><option value='Gibraltar' data-id='84'>Gibraltar<\/option><option value='Greece' data-id='85'>Greece<\/option><option value='Greenland' data-id='86'>Greenland<\/option><option value='Grenada' data-id='87'>Grenada<\/option><option value='Guadeloupe' data-id='88'>Guadeloupe<\/option><option value='Guam' data-id='89'>Guam<\/option><option value='Guatemala' data-id='90'>Guatemala<\/option><option value='Guernsey and Alderney' data-id='91'>Guernsey and Alderney<\/option><option value='Guinea' data-id='92'>Guinea<\/option><option value='Guinea-Bissau' data-id='93'>Guinea-Bissau<\/option><option value='Guyana' data-id='94'>Guyana<\/option><option value='Haiti' data-id='95'>Haiti<\/option><option value='Heard and McDonald Islands' data-id='96'>Heard and McDonald Islands<\/option><option value='Honduras' data-id='97'>Honduras<\/option><option value='Hong Kong S.A.R.' data-id='98'>Hong Kong S.A.R.<\/option><option value='Hungary' data-id='99'>Hungary<\/option><option value='Iceland' data-id='100'>Iceland<\/option><option value='India' data-id='101'>India<\/option><option value='Indonesia' data-id='102'>Indonesia<\/option><option value='Iran' data-id='103'>Iran<\/option><option value='Iraq' data-id='104'>Iraq<\/option><option value='Ireland' data-id='105'>Ireland<\/option><option value='Israel' data-id='106'>Israel<\/option><option value='Italy' data-id='107'>Italy<\/option><option value='Jamaica' data-id='108'>Jamaica<\/option><option value='Japan' data-id='109'>Japan<\/option><option value='Jersey' data-id='110'>Jersey<\/option><option value='Jordan' data-id='111'>Jordan<\/option><option value='Kazakhstan' data-id='112'>Kazakhstan<\/option><option value='Kenya' data-id='113'>Kenya<\/option><option value='Kiribati' data-id='114'>Kiribati<\/option><option value='Korea North' data-id='115'>Korea North<\/option><option value='Korea South' data-id='116'>Korea South<\/option><option value='Kuwait' data-id='117'>Kuwait<\/option><option value='Kyrgyzstan' data-id='118'>Kyrgyzstan<\/option><option value='Laos' data-id='119'>Laos<\/option><option value='Latvia' data-id='120'>Latvia<\/option><option value='Lebanon' data-id='121'>Lebanon<\/option><option value='Lesotho' data-id='122'>Lesotho<\/option><option value='Liberia' data-id='123'>Liberia<\/option><option value='Libya' data-id='124'>Libya<\/option><option value='Liechtenstein' data-id='125'>Liechtenstein<\/option><option value='Lithuania' data-id='126'>Lithuania<\/option><option value='Luxembourg' data-id='127'>Luxembourg<\/option><option value='Macau S.A.R.' data-id='128'>Macau S.A.R.<\/option><option value='Macedonia' data-id='129'>Macedonia<\/option><option value='Madagascar' data-id='130'>Madagascar<\/option><option value='Malawi' data-id='131'>Malawi<\/option><option value='Malaysia' data-id='132'>Malaysia<\/option><option value='Maldives' data-id='133'>Maldives<\/option><option value='Mali' data-id='134'>Mali<\/option><option value='Malta' data-id='135'>Malta<\/option><option value='Man (Isle of)' data-id='136'>Man (Isle of)<\/option><option value='Marshall Islands' data-id='137'>Marshall Islands<\/option><option value='Martinique' data-id='138'>Martinique<\/option><option value='Mauritania' data-id='139'>Mauritania<\/option><option value='Mauritius' data-id='140'>Mauritius<\/option><option value='Mayotte' data-id='141'>Mayotte<\/option><option value='Mexico' data-id='142'>Mexico<\/option><option value='Micronesia' data-id='143'>Micronesia<\/option><option value='Moldova' data-id='144'>Moldova<\/option><option value='Monaco' data-id='145'>Monaco<\/option><option value='Mongolia' data-id='146'>Mongolia<\/option><option value='Montenegro' data-id='147'>Montenegro<\/option><option value='Montserrat' data-id='148'>Montserrat<\/option><option value='Morocco' data-id='149'>Morocco<\/option><option value='Mozambique' data-id='150'>Mozambique<\/option><option value='Myanmar' data-id='151'>Myanmar<\/option><option value='Namibia' data-id='152'>Namibia<\/option><option value='Nauru' data-id='153'>Nauru<\/option><option value='Nepal' data-id='154'>Nepal<\/option><option value='Netherlands Antilles' data-id='155'>Netherlands Antilles<\/option><option value='Netherlands The' data-id='156'>Netherlands The<\/option><option value='New Caledonia' data-id='157'>New Caledonia<\/option><option value='New Zealand' data-id='158'>New Zealand<\/option><option value='Nicaragua' data-id='159'>Nicaragua<\/option><option value='Niger' data-id='160'>Niger<\/option><option value='Nigeria' data-id='161'>Nigeria<\/option><option value='Niue' data-id='162'>Niue<\/option><option value='Norfolk Island' data-id='163'>Norfolk Island<\/option><option value='Northern Mariana Islands' data-id='164'>Northern Mariana Islands<\/option><option value='Norway' data-id='165'>Norway<\/option><option value='Oman' data-id='166'>Oman<\/option><option value='Pakistan' data-id='167'>Pakistan<\/option><option value='Palau' data-id='168'>Palau<\/option><option value='Palestinian Territory Occupied' data-id='169'>Palestinian Territory Occupied<\/option><option value='Panama' data-id='170'>Panama<\/option><option value='Papua new Guinea' data-id='171'>Papua new Guinea<\/option><option value='Paraguay' data-id='172'>Paraguay<\/option><option value='Peru' data-id='173'>Peru<\/option><option value='Philippines' data-id='174'>Philippines<\/option><option value='Pitcairn Island' data-id='175'>Pitcairn Island<\/option><option value='Poland' data-id='176'>Poland<\/option><option value='Portugal' data-id='177'>Portugal<\/option><option value='Puerto Rico' data-id='178'>Puerto Rico<\/option><option value='Qatar' data-id='179'>Qatar<\/option><option value='Reunion' data-id='180'>Reunion<\/option><option value='Romania' data-id='181'>Romania<\/option><option value='Russia' data-id='182'>Russia<\/option><option value='Rwanda' data-id='183'>Rwanda<\/option><option value='Saint Helena' data-id='184'>Saint Helena<\/option><option value='Saint Kitts And Nevis' data-id='185'>Saint Kitts And Nevis<\/option><option value='Saint Lucia' data-id='186'>Saint Lucia<\/option><option value='Saint Pierre and Miquelon' data-id='187'>Saint Pierre and Miquelon<\/option><option value='Saint Vincent And The Grenadines' data-id='188'>Saint Vincent And The Grenadines<\/option><option value='Saint-Barthelemy' data-id='189'>Saint-Barthelemy<\/option><option value='Saint-Martin (French part)' data-id='190'>Saint-Martin (French part)<\/option><option value='Samoa' data-id='191'>Samoa<\/option><option value='San Marino' data-id='192'>San Marino<\/option><option value='Sao Tome and Principe' data-id='193'>Sao Tome and Principe<\/option><option value='Saudi Arabia' data-id='194'>Saudi Arabia<\/option><option value='Senegal' data-id='195'>Senegal<\/option><option value='Serbia' data-id='196'>Serbia<\/option><option value='Seychelles' data-id='197'>Seychelles<\/option><option value='Sierra Leone' data-id='198'>Sierra Leone<\/option><option value='Singapore' data-id='199'>Singapore<\/option><option value='Slovakia' data-id='200'>Slovakia<\/option><option value='Slovenia' data-id='201'>Slovenia<\/option><option value='Solomon Islands' data-id='202'>Solomon Islands<\/option><option value='Somalia' data-id='203'>Somalia<\/option><option value='South Africa' data-id='204'>South Africa<\/option><option value='South Georgia' data-id='205'>South Georgia<\/option><option value='South Sudan' data-id='206'>South Sudan<\/option><option value='Spain' data-id='207'>Spain<\/option><option value='Sri Lanka' data-id='208'>Sri Lanka<\/option><option value='Sudan' data-id='209'>Sudan<\/option><option value='Suriname' data-id='210'>Suriname<\/option><option value='Svalbard And Jan Mayen Islands' data-id='211'>Svalbard And Jan Mayen Islands<\/option><option value='Swaziland' data-id='212'>Swaziland<\/option><option value='Sweden' data-id='213'>Sweden<\/option><option value='Switzerland' data-id='214'>Switzerland<\/option><option value='Syria' data-id='215'>Syria<\/option><option value='Taiwan' data-id='216'>Taiwan<\/option><option value='Tajikistan' data-id='217'>Tajikistan<\/option><option value='Tanzania' data-id='218'>Tanzania<\/option><option value='Thailand' data-id='219'>Thailand<\/option><option value='Togo' data-id='220'>Togo<\/option><option value='Tokelau' data-id='221'>Tokelau<\/option><option value='Tonga' data-id='222'>Tonga<\/option><option value='Trinidad And Tobago' data-id='223'>Trinidad And Tobago<\/option><option value='Tunisia' data-id='224'>Tunisia<\/option><option value='Turkey' data-id='225'>Turkey<\/option><option value='Turkmenistan' data-id='226'>Turkmenistan<\/option><option value='Turks And Caicos Islands' data-id='227'>Turks And Caicos Islands<\/option><option value='Tuvalu' data-id='228'>Tuvalu<\/option><option value='Uganda' data-id='229'>Uganda<\/option><option value='Ukraine' data-id='230'>Ukraine<\/option><option value='United Arab Emirates' data-id='231'>United Arab Emirates<\/option><option value='United Kingdom' data-id='232'>United Kingdom<\/option><option value='United States' data-id='233'>United States<\/option><option value='United States Minor Outlying Islands' data-id='234'>United States Minor Outlying Islands<\/option><option value='Uruguay' data-id='235'>Uruguay<\/option><option value='Uzbekistan' data-id='236'>Uzbekistan<\/option><option value='Vanuatu' data-id='237'>Vanuatu<\/option><option value='Vatican City State (Holy See)' data-id='238'>Vatican City State (Holy See)<\/option><option value='Venezuela' data-id='239'>Venezuela<\/option><option value='Vietnam' data-id='240'>Vietnam<\/option><option value='Virgin Islands (British)' data-id='241'>Virgin Islands (British)<\/option><option value='Virgin Islands (US)' data-id='242'>Virgin Islands (US)<\/option><option value='Wallis And Futuna Islands' data-id='243'>Wallis And Futuna Islands<\/option><option value='Western Sahara' data-id='244'>Western Sahara<\/option><option value='Yemen' data-id='245'>Yemen<\/option><option value='Zambia' data-id='246'>Zambia<\/option><option value='Zimbabwe' data-id='247'>Zimbabwe<\/option><\/select><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap state_auto your-state\"><select class=\"wpcf7-form-control wpcf7-select state_auto wpcf7-state_auto wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-state\" ><option value=\"0\" data-id=\"0\">Select State<\/option><\/select><\/span>\n\t<\/p>\n<\/div>\n<div class=\"wpcf7-inline-wrapper\">\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-city\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your City\" value=\"\" type=\"text\" name=\"your-city\" \/><\/span>\n\t<\/p>\n\t<p class=\"wpcf7-inline-field\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-zip\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-fluid\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your ZIP code\" value=\"\" type=\"text\" name=\"your-zip\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"8\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Your message.\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><span id=\"wpcf7-6a97c8f8bb98b-wrapper\" class=\"wpcf7-form-control-wrap word-445-wrap\" ><label for=\"wpcf7-6a97c8f8bb98b-field\" class=\"hp-message\">Please leave this field empty.<\/label><input id=\"wpcf7-6a97c8f8bb98b-field\"  placeholder=\"Your word\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"word-445\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-678\"><label><span class=\"wpcf7-quiz-label\">What number is larger 7 or 4?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-678\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-678\" value=\"afa0d208077f310537af0da837028721\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit btn btn-accent btn-circle\" type=\"submit\" value=\"Submit\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>[vc_section back_color=&#8221;color-lxmt&#8221; overlay_alpha=&#8221;50&#8243; el_class=&#8221;contact-world-map&#8221;][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;2&#8243; top_padding=&#8221;3&#8243; bottom_padding=&#8221;3&#8243; back_color=&#8221;color-xsdn&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243;][vc_column column_width_use_pixel=&#8221;yes&#8221; align_horizontal=&#8221;align_center&#8221; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact - mk Solutions<\/title>\n<meta name=\"description\" content=\"Contact\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mksolutions.com\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - mk Solutions\" \/>\n<meta property=\"og:description\" content=\"Contact\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mksolutions.com\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"mk Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T14:07:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mksolutions.com\/en\/contact\/\",\"url\":\"https:\/\/www.mksolutions.com\/en\/contact\/\",\"name\":\"Contact - mk Solutions\",\"isPartOf\":{\"@id\":\"https:\/\/www.mksolutions.com\/en\/#website\"},\"datePublished\":\"2017-06-09T16:37:51+00:00\",\"dateModified\":\"2023-03-20T14:07:57+00:00\",\"description\":\"Contact\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mksolutions.com\/en\/contact\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mksolutions.com\/en\/contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mksolutions.com\/en\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mksolutions.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mksolutions.com\/en\/#website\",\"url\":\"https:\/\/www.mksolutions.com\/en\/\",\"name\":\"mk Solutions\",\"description\":\"library automation with smart solutions\",\"publisher\":{\"@id\":\"https:\/\/www.mksolutions.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mksolutions.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mksolutions.com\/en\/#organization\",\"name\":\"mk solution\",\"url\":\"https:\/\/www.mksolutions.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mksolutions.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mksolutions.com\/wp-content\/uploads\/2017\/05\/cropped-mk_solutions_website_icon.png\",\"contentUrl\":\"https:\/\/www.mksolutions.com\/wp-content\/uploads\/2017\/05\/cropped-mk_solutions_website_icon.png\",\"width\":512,\"height\":512,\"caption\":\"mk solution\"},\"image\":{\"@id\":\"https:\/\/www.mksolutions.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - mk Solutions","description":"Contact","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mksolutions.com\/en\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact - mk Solutions","og_description":"Contact","og_url":"https:\/\/www.mksolutions.com\/en\/contact\/","og_site_name":"mk Solutions","article_modified_time":"2023-03-20T14:07:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mksolutions.com\/en\/contact\/","url":"https:\/\/www.mksolutions.com\/en\/contact\/","name":"Contact - mk Solutions","isPartOf":{"@id":"https:\/\/www.mksolutions.com\/en\/#website"},"datePublished":"2017-06-09T16:37:51+00:00","dateModified":"2023-03-20T14:07:57+00:00","description":"Contact","breadcrumb":{"@id":"https:\/\/www.mksolutions.com\/en\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mksolutions.com\/en\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mksolutions.com\/en\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mksolutions.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.mksolutions.com\/en\/#website","url":"https:\/\/www.mksolutions.com\/en\/","name":"mk Solutions","description":"library automation with smart solutions","publisher":{"@id":"https:\/\/www.mksolutions.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mksolutions.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.mksolutions.com\/en\/#organization","name":"mk solution","url":"https:\/\/www.mksolutions.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mksolutions.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.mksolutions.com\/wp-content\/uploads\/2017\/05\/cropped-mk_solutions_website_icon.png","contentUrl":"https:\/\/www.mksolutions.com\/wp-content\/uploads\/2017\/05\/cropped-mk_solutions_website_icon.png","width":512,"height":512,"caption":"mk solution"},"image":{"@id":"https:\/\/www.mksolutions.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/pages\/58781"}],"collection":[{"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/comments?post=58781"}],"version-history":[{"count":145,"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/pages\/58781\/revisions"}],"predecessor-version":[{"id":63619,"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/pages\/58781\/revisions\/63619"}],"wp:attachment":[{"href":"https:\/\/www.mksolutions.com\/en\/wp-json\/wp\/v2\/media?parent=58781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}